{"id":6086,"date":"2010-01-12T18:04:45","date_gmt":"2010-01-12T18:04:45","guid":{"rendered":"https:\/\/label-design.es\/sanjose\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/"},"modified":"2010-01-12T18:04:45","modified_gmt":"2010-01-12T18:04:45","slug":"sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo","status":"publish","type":"post","link":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/","title":{"rendered":"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<div>\n<p align=\"justify\">La asociaci\u00f3n Gure Etxea lleva canalizando desde hace a\u00f1os buena parte de las reclamaciones que los vecinos de Uribarri realizan a causa de resbalones y ca\u00eddas. Para ellos, esta sentencia marca un hito al ser la primera resoluci\u00f3n favorable en la ciudad sobre resbalones. Un problema que, seg\u00fan estos vecinos, tiene su origen \u00aben el cambio de las baldosas de las calles hace unos a\u00f1os\u00bb. Para Xabier Bilbao, letrado demandante, \u00abesta resoluci\u00f3n puede servir para que otros casos similares puedan solucionarse por la v\u00eda administrativa\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p align=\"justify\">La Justicia ha dado la raz\u00f3n a un vecino de Uribarri, asistido por el miembro de nuestro Despacho\u00a0<a class=\"wpGallery\" title=\"xabier bilbao\" href=\"http:\/\/sanjoseabogados.com\/abogados\/xabierbilbaoormazabals\" target=\"_self\" rel=\"noopener noreferrer\">Xabier Bilbao<\/a>,\u00a0por uno de los continuos episodios de resbalones y ca\u00eddas que sufren los habitantes de este barrio bilba\u00edno. Una sentencia del Juzgado de lo Contencioso Administrativo n\u00famero 4 de Bilbao respalda a J.M.R y condena al Consistorio de la capital vizca\u00edna a indemnizarle con 8.455,90 euros -m\u00e1s intereses- por los da\u00f1os que sufri\u00f3 en 2006 tras una ca\u00edda en la esquina de la calle Monte Arno con Trauko.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"justify\">La Sentencia de un cliente de <strong>San Jos\u00e9 Abogados<\/strong> fue noticia en <a class=\"wpGallery\" title=\"noticia\" href=\"http:\/\/www.elcorreo.com\/vizcaya\/20100112\/vizcaya\/vecino-uribarri-recibira-euros-20100112.html\" target=\"_blank\" rel=\"noopener noreferrer\">elcorreo.com.<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La asociaci\u00f3n Gure Etxea lleva canalizando desde hace a\u00f1os buena parte de las reclamaciones que los vecinos de Uribarri realizan a causa de resbalones y ca\u00eddas. Para ellos, esta sentencia marca un hito al ser la primera resoluci\u00f3n favorable en la ciudad sobre resbalones.\t\t\t\t\t<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[423],"tags":[928,929,930],"class_list":["post-6086","post","type-post","status-publish","format-standard","hentry","category-noticia-en","tag-caida-en-la-calle-en","tag-condena-al-ayuntamiento-en","tag-indemnizacion-danos-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo - Despacho Abogados San Jose<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo - Despacho Abogados San Jose\" \/>\n<meta property=\"og:description\" content=\"La asociaci\u00f3n Gure Etxea lleva canalizando desde hace a\u00f1os buena parte de las reclamaciones que los vecinos de Uribarri realizan a causa de resbalones y ca\u00eddas. Para ellos, esta sentencia marca un hito al ser la primera resoluci\u00f3n favorable en la ciudad sobre resbalones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/\" \/>\n<meta property=\"og:site_name\" content=\"Despacho Abogados San Jose\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-12T18:04:45+00:00\" \/>\n<meta name=\"author\" content=\"San Jose Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"San Jose Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/\"},\"author\":{\"name\":\"San Jose Abogados\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#\\\/schema\\\/person\\\/9598f83ebb435fbe592f66dd5d3f7c6d\"},\"headline\":\"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo\",\"datePublished\":\"2010-01-12T18:04:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/\"},\"wordCount\":215,\"keywords\":[\"Ca\u00edda en la calle\",\"Condena al Ayuntamiento\",\"Indemnizaci\u00f3n da\u00f1os\"],\"articleSection\":[\"3. Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/\",\"url\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/\",\"name\":\"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo - Despacho Abogados San Jose\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#website\"},\"datePublished\":\"2010-01-12T18:04:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#\\\/schema\\\/person\\\/9598f83ebb435fbe592f66dd5d3f7c6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/\",\"name\":\"Despacho Abogados San Jose\",\"description\":\"Despacho abogados en Bilbao\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#\\\/schema\\\/person\\\/9598f83ebb435fbe592f66dd5d3f7c6d\",\"name\":\"San Jose Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g\",\"caption\":\"San Jose Abogados\"},\"url\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/author\\\/san-jose-abogados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo - Despacho Abogados San Jose","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/","og_locale":"en_US","og_type":"article","og_title":"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo - Despacho Abogados San Jose","og_description":"La asociaci\u00f3n Gure Etxea lleva canalizando desde hace a\u00f1os buena parte de las reclamaciones que los vecinos de Uribarri realizan a causa de resbalones y ca\u00eddas. Para ellos, esta sentencia marca un hito al ser la primera resoluci\u00f3n favorable en la ciudad sobre resbalones.","og_url":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/","og_site_name":"Despacho Abogados San Jose","article_published_time":"2010-01-12T18:04:45+00:00","author":"San Jose Abogados","twitter_card":"summary_large_image","twitter_misc":{"Written by":"San Jose Abogados","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/#article","isPartOf":{"@id":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/"},"author":{"name":"San Jose Abogados","@id":"https:\/\/sanjoseabogados.com\/en\/#\/schema\/person\/9598f83ebb435fbe592f66dd5d3f7c6d"},"headline":"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo","datePublished":"2010-01-12T18:04:45+00:00","mainEntityOfPage":{"@id":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/"},"wordCount":215,"keywords":["Ca\u00edda en la calle","Condena al Ayuntamiento","Indemnizaci\u00f3n da\u00f1os"],"articleSection":["3. Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/","url":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/","name":"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo - Despacho Abogados San Jose","isPartOf":{"@id":"https:\/\/sanjoseabogados.com\/en\/#website"},"datePublished":"2010-01-12T18:04:45+00:00","author":{"@id":"https:\/\/sanjoseabogados.com\/en\/#\/schema\/person\/9598f83ebb435fbe592f66dd5d3f7c6d"},"breadcrumb":{"@id":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sanjoseabogados.com\/en\/sentencia-un-vecino-de-uribarri-recibira-8-455-euros-por-un-patinazo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanjoseabogados.com\/en\/"},{"@type":"ListItem","position":2,"name":"Sentencia: Un vecino de Uribarri recibir\u00e1 8.455 euros por un patinazo"}]},{"@type":"WebSite","@id":"https:\/\/sanjoseabogados.com\/en\/#website","url":"https:\/\/sanjoseabogados.com\/en\/","name":"Despacho Abogados San Jose","description":"Despacho abogados en Bilbao","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanjoseabogados.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sanjoseabogados.com\/en\/#\/schema\/person\/9598f83ebb435fbe592f66dd5d3f7c6d","name":"San Jose Abogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g","caption":"San Jose Abogados"},"url":"https:\/\/sanjoseabogados.com\/en\/author\/san-jose-abogados\/"}]}},"_links":{"self":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/posts\/6086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/comments?post=6086"}],"version-history":[{"count":0,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/posts\/6086\/revisions"}],"wp:attachment":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/media?parent=6086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/categories?post=6086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/tags?post=6086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}