{"id":7649,"date":"2020-04-27T12:36:23","date_gmt":"2020-04-27T10:36:23","guid":{"rendered":"https:\/\/sanjoseabogados.com\/hechos-consumados-y-derecho-de-familia\/"},"modified":"2020-08-09T17:08:15","modified_gmt":"2020-08-09T15:08:15","slug":"hechos-consumados-y-derecho-de-familia","status":"publish","type":"post","link":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/","title":{"rendered":"ALGO FALLA &#8211; Hechos consumados y derecho de familia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-portfolio wp-image-7232\" src=\"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg\" alt=\"\" width=\"495\" height=\"400\" srcset=\"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg 495w, https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-845x684.jpg 845w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/p>\n<p>Hay una explicaci\u00f3n recurrente que nos vemos obligados a utilizar con nuestros clientes cuando, dolidos por la actuaci\u00f3n de su ex pareja, nos preguntan qu\u00e9 pueden hacer:<em> \u201cel derecho\u00a0 de familia llega tarde en la mayor\u00eda de las ocasiones\u201d.<\/em><\/p>\n<p>Nos referimos a casos en los que el <em>progenitor<\/em> no entrega al menor en la fecha y hora acordadas para el disfrute de vacaciones, o impide la comunicaci\u00f3n telef\u00f3nica establecida, o se niega a que el ni\u00f1o acuda a clases de refuerzo, o llega media hora tarde a las visitas, o no administra la medicaci\u00f3n que necesita su hijo,\u2026<\/p>\n<p>Los supuestos son incontables, como incontables son las veces en que algunos <em>progenitores<\/em> incumplen los mandatos judiciales y atentan contra los derechos de sus hijos, mediante la <strong>v\u00eda de los hechos consumados<\/strong>.<\/p>\n<p>Esto coloca a los profesionales del derecho en una situaci\u00f3n compleja, porque resulta imposible satisfacer la leg\u00edtima pretensi\u00f3n del cliente de que su hijo no resulte perjudicado por el comportamiento del otro progenitor, evitando incumplimientos como los que han sido explicados.<\/p>\n<p>Y es que desgraciadamente no existen instrumentos jur\u00eddicos \u00e1giles para impedir que un progenitor no entregue a un menor cuando le corresponde, por poner un ejemplo.<\/p>\n<p>El <strong>C\u00f3digo Civil<\/strong> tiene art\u00edculos como el <strong>158<\/strong>, cuya finalidad es que un Juez establezca, de manera <strong>urgente<\/strong>, medidas que corrijan los referidos comportamientos, pero la realidad es que si un progenitor acude a recoger a un menor al domicilio del otro progenitor, porque le corresponde disfrutar de sus vacaciones de Semana Santa desde el 4 de abril al 11 de abril, y su ex pareja no est\u00e1 en el domicilio, porque ha decidido <strong>por la v\u00eda de hecho<\/strong> disfrutar de esos mismos d\u00edas con el menor, no existe un instrumento jur\u00eddico que corrija tal comportamiento y le permita disfrutar de las vacaciones con su hijo.<\/p>\n<p>La realidad es que en esos casos el progenitor incumplidor se habr\u00e1 salido con la suya, y el progenitor afectado a lo sumo podr\u00e1 aspirar a que se dicte una resoluci\u00f3n <strong>(meses despu\u00e9s de las vacaciones)<\/strong> que repruebe el comportamiento del incumplidor, sin mayores consecuencias.<\/p>\n<p>El efecto perverso de la falta de instrumentos jur\u00eddicos es que dichos comportamientos incumplidores se multiplican, porque quien los lleva a cabo sabe &#8211; o su abogado se encarga de hacerle saber -, que va a poder hacer lo que desee, habida cuenta de que su ex pareja no va a tener recursos para imped\u00edrselo.<\/p>\n<p><strong>ALGO FALLA<\/strong> cuando el legislador no dota de medios suficientes a los jueces para que puedan poner fin a la <strong>v\u00eda de hechos consumados<\/strong>, resolviendo un problema recurrente que afecta a miles de menores, y por extensi\u00f3n, a miles de progenitores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay una explicaci\u00f3n recurrente que nos vemos obligados a utilizar con nuestros clientes cuando, dolidos por la actuaci\u00f3n de su ex pareja, nos preguntan qu\u00e9 pueden hacer: \u201cel derecho\u00a0 de familia llega tarde en la mayor\u00eda de las ocasiones\u201d.<\/p>\n<p>Nos referimos a casos en los que el progenitor no entrega al menor en la fecha y hora acordadas para el disfrute de vacaciones, o impide la comunicaci\u00f3n telef\u00f3nica establecida, o se niega a que el ni\u00f1o acuda a clases de refuerzo, o llega media hora tarde a las visitas, o no administra la medicaci\u00f3n que necesita su hijo,\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1209,423],"tags":[1236,939,1237],"class_list":["post-7649","post","type-post","status-publish","format-standard","hentry","category-algo-falla-en","category-noticia-en","tag-abogados-familia-en","tag-derecho-de-familia-en","tag-progenitor-incumplidor-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALGO FALLA - Hechos consumados y derecho de familia - Despacho Abogados San Jose<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALGO FALLA - Hechos consumados y derecho de familia - Despacho Abogados San Jose\" \/>\n<meta property=\"og:description\" content=\"Hay una explicaci\u00f3n recurrente que nos vemos obligados a utilizar con nuestros clientes cuando, dolidos por la actuaci\u00f3n de su ex pareja, nos preguntan qu\u00e9 pueden hacer: \u201cel derecho\u00a0 de familia llega tarde en la mayor\u00eda de las ocasiones\u201d.  Nos referimos a casos en los que el progenitor no entrega al menor en la fecha y hora acordadas para el disfrute de vacaciones, o impide la comunicaci\u00f3n telef\u00f3nica establecida, o se niega a que el ni\u00f1o acuda a clases de refuerzo, o llega media hora tarde a las visitas, o no administra la medicaci\u00f3n que necesita su hijo,\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"Despacho Abogados San Jose\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T10:36:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T15:08:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg\" \/>\n<meta name=\"author\" content=\"San Jose Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"San Jose Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/\"},\"author\":{\"name\":\"San Jose Abogados\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#\\\/schema\\\/person\\\/9598f83ebb435fbe592f66dd5d3f7c6d\"},\"headline\":\"ALGO FALLA &#8211; Hechos consumados y derecho de familia\",\"datePublished\":\"2020-04-27T10:36:23+00:00\",\"dateModified\":\"2020-08-09T15:08:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/\"},\"wordCount\":473,\"image\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanjoseabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Progenitor-incumplidor-495x400.jpg\",\"keywords\":[\"abogados familia\",\"Derecho de Familia\",\"progenitor incumplidor\"],\"articleSection\":[\"1. ALGO FALLA\",\"3. Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/\",\"url\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/\",\"name\":\"ALGO FALLA - Hechos consumados y derecho de familia - Despacho Abogados San Jose\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sanjoseabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Progenitor-incumplidor-495x400.jpg\",\"datePublished\":\"2020-04-27T10:36:23+00:00\",\"dateModified\":\"2020-08-09T15:08:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#\\\/schema\\\/person\\\/9598f83ebb435fbe592f66dd5d3f7c6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sanjoseabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Progenitor-incumplidor-495x400.jpg\",\"contentUrl\":\"https:\\\/\\\/sanjoseabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Progenitor-incumplidor-495x400.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/hechos-consumados-y-derecho-de-familia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALGO FALLA &#8211; Hechos consumados y derecho de familia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/\",\"name\":\"Despacho Abogados San Jose\",\"description\":\"Despacho abogados en Bilbao\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/#\\\/schema\\\/person\\\/9598f83ebb435fbe592f66dd5d3f7c6d\",\"name\":\"San Jose Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g\",\"caption\":\"San Jose Abogados\"},\"url\":\"https:\\\/\\\/sanjoseabogados.com\\\/en\\\/author\\\/san-jose-abogados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALGO FALLA - Hechos consumados y derecho de familia - Despacho Abogados San Jose","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/","og_locale":"en_US","og_type":"article","og_title":"ALGO FALLA - Hechos consumados y derecho de familia - Despacho Abogados San Jose","og_description":"Hay una explicaci\u00f3n recurrente que nos vemos obligados a utilizar con nuestros clientes cuando, dolidos por la actuaci\u00f3n de su ex pareja, nos preguntan qu\u00e9 pueden hacer: \u201cel derecho\u00a0 de familia llega tarde en la mayor\u00eda de las ocasiones\u201d.  Nos referimos a casos en los que el progenitor no entrega al menor en la fecha y hora acordadas para el disfrute de vacaciones, o impide la comunicaci\u00f3n telef\u00f3nica establecida, o se niega a que el ni\u00f1o acuda a clases de refuerzo, o llega media hora tarde a las visitas, o no administra la medicaci\u00f3n que necesita su hijo,\u2026","og_url":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/","og_site_name":"Despacho Abogados San Jose","article_published_time":"2020-04-27T10:36:23+00:00","article_modified_time":"2020-08-09T15:08:15+00:00","og_image":[{"url":"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg","type":"","width":"","height":""}],"author":"San Jose Abogados","twitter_card":"summary_large_image","twitter_misc":{"Written by":"San Jose Abogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/#article","isPartOf":{"@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/"},"author":{"name":"San Jose Abogados","@id":"https:\/\/sanjoseabogados.com\/en\/#\/schema\/person\/9598f83ebb435fbe592f66dd5d3f7c6d"},"headline":"ALGO FALLA &#8211; Hechos consumados y derecho de familia","datePublished":"2020-04-27T10:36:23+00:00","dateModified":"2020-08-09T15:08:15+00:00","mainEntityOfPage":{"@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/"},"wordCount":473,"image":{"@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg","keywords":["abogados familia","Derecho de Familia","progenitor incumplidor"],"articleSection":["1. ALGO FALLA","3. Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/","url":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/","name":"ALGO FALLA - Hechos consumados y derecho de familia - Despacho Abogados San Jose","isPartOf":{"@id":"https:\/\/sanjoseabogados.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/#primaryimage"},"image":{"@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg","datePublished":"2020-04-27T10:36:23+00:00","dateModified":"2020-08-09T15:08:15+00:00","author":{"@id":"https:\/\/sanjoseabogados.com\/en\/#\/schema\/person\/9598f83ebb435fbe592f66dd5d3f7c6d"},"breadcrumb":{"@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/#primaryimage","url":"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg","contentUrl":"https:\/\/sanjoseabogados.com\/wp-content\/uploads\/2020\/04\/Progenitor-incumplidor-495x400.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/sanjoseabogados.com\/en\/hechos-consumados-y-derecho-de-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sanjoseabogados.com\/en\/"},{"@type":"ListItem","position":2,"name":"ALGO FALLA &#8211; Hechos consumados y derecho de familia"}]},{"@type":"WebSite","@id":"https:\/\/sanjoseabogados.com\/en\/#website","url":"https:\/\/sanjoseabogados.com\/en\/","name":"Despacho Abogados San Jose","description":"Despacho abogados en Bilbao","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sanjoseabogados.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sanjoseabogados.com\/en\/#\/schema\/person\/9598f83ebb435fbe592f66dd5d3f7c6d","name":"San Jose Abogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/426c26975de8e4468f967881881cf37d598c65f2818563162b0fada43d69a5fc?s=96&d=mm&r=g","caption":"San Jose Abogados"},"url":"https:\/\/sanjoseabogados.com\/en\/author\/san-jose-abogados\/"}]}},"_links":{"self":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/posts\/7649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/comments?post=7649"}],"version-history":[{"count":1,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/posts\/7649\/revisions"}],"predecessor-version":[{"id":7650,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/posts\/7649\/revisions\/7650"}],"wp:attachment":[{"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/media?parent=7649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/categories?post=7649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanjoseabogados.com\/en\/wp-json\/wp\/v2\/tags?post=7649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}